{"id":41251,"date":"2023-04-15T09:00:20","date_gmt":"2023-04-15T07:00:20","guid":{"rendered":"https:\/\/www.nimms-rad.de\/news\/?p=41251"},"modified":"2024-01-12T13:35:46","modified_gmt":"2024-01-12T12:35:46","slug":"monopol-toolbike-no-01-lastenrad","status":"publish","type":"post","link":"https:\/\/www.nimms-rad.de\/news\/monopol-toolbike-no-01-lastenrad\/","title":{"rendered":"Monopole Toolbike No 01 Lastenrad: Das Schweizer Taschenmesser unter den Cargobikes"},"content":{"rendered":"<!-- toc shortcode skipped: 5054471733 --><p><strong>Mit dem Toolbike No 01 stellt die Schweizer Marke Monopole ihr erstes Lastenrad vor \u2013 das Gef\u00e4hrt l\u00e4uft mit elektrischer Unterst\u00fctzung, besitzt eine Riemenlenkung, ist in 3 Gr\u00f6\u00dfen erh\u00e4ltlich und der Rahmen wird in Europa hergestellt. Dabei soll das Lastenrad nicht nur funktionell sein, sondern auch in Puncto Design punkten!<\/strong><\/p>\n<p>[toc]<\/p>\n<p>Auffallend anders ist das Monopole Toolbike No 01 \u2013 in der Schweiz entwickelt und in den franz\u00f6sischen Pyren\u00e4en von Hand geschwei\u00dft und montiert m\u00f6chte das <a title=\"Lastenrad\" href=\"https:\/\/www.nimms-rad.de\/news\/lastenrad-cargobike\/\" rel=\"noopener\">Lastenrad<\/a> mehr sein, als blo\u00dfes Werkzeug f\u00fcr das urbane Leben. Auch das Design spielt bei Monopole eine wichtige Rolle, wobei die Reduzierung auf das Wesentliche ein Kernpunkt der Marke ist, ohne die Funktionalit\u00e4t zu vernachl\u00e4ssigen. Das scheint ihnen beim Toolbike gelungen zu sein.<\/p>\n<div class=\"js__imageWrap n_post-image-wrap \"><figure class=\"n_post-image\">\n        <a id=\"fa-photo-4916\"><\/a>\n        <a href=\"https:\/\/fotos.nimms-rad.de\/p\/4916\" title=\"Das Toolbike No 01 von Monopole sieht nicht nur sehr schick aus, es ist zudem auch funktional und durchdacht.\">\n            <img decoding=\"async\"\n                src=\"https:\/\/images.mtb-news.de\/XL2fc1wETkJvOSij8fDNwb8vJPk=\/320x202\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4916-ceeqf20wozwt-1678817505_monopole_2022_164-original.jpg\"\n                srcset=\"https:\/\/images.mtb-news.de\/GOq_u50DNTuBR7MXFx4oka2HitE=\/2400x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4916-ceeqf20wozwt-1678817505_monopole_2022_164-original.jpg 2400w, https:\/\/images.mtb-news.de\/9Kuzjt8n4stHacYT1wuPYSFJ7ts=\/1200x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4916-ceeqf20wozwt-1678817505_monopole_2022_164-original.jpg 1200w, https:\/\/images.mtb-news.de\/4i4HKl4ZKKFaYa3cEdiCwgOmv0o=\/2000x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4916-ceeqf20wozwt-1678817505_monopole_2022_164-original.jpg 2000w, https:\/\/images.mtb-news.de\/hNqN5-rQGRVSCtXoW9uvGPJsT_8=\/1000x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4916-ceeqf20wozwt-1678817505_monopole_2022_164-original.jpg 1000w, https:\/\/images.mtb-news.de\/4KlqkVHxbs9obHo80BTf2wBzj8A=\/1500x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4916-ceeqf20wozwt-1678817505_monopole_2022_164-original.jpg 1500w, https:\/\/images.mtb-news.de\/neVC9RMhcZMJoHtW8-4LSgXOKcQ=\/750x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4916-ceeqf20wozwt-1678817505_monopole_2022_164-original.jpg 750w, https:\/\/images.mtb-news.de\/pOLmhTZxFv9QyQkXA9D1yEgymhg=\/480x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4916-ceeqf20wozwt-1678817505_monopole_2022_164-original.jpg 480w, https:\/\/images.mtb-news.de\/NdS7To7RGlua_TpMUu5ERGzKw1k=\/320x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4916-ceeqf20wozwt-1678817505_monopole_2022_164-original.jpg 320w\"\n                sizes=\"auto, (min-width: 980px) 980px, (min-width: 768px) 750px, (min-width: 481px) 720px, 100vw\"\n                loading=\"lazy\"\n                alt=\"Das Toolbike No 01 von Monopole sieht nicht nur sehr schick aus, es ist zudem auch funktional und durchdacht.\"\n                title=\"Das Toolbike No 01 von Monopole sieht nicht nur sehr schick aus, es ist zudem auch funktional und durchdacht.\"\n                data-photo-id=\"4916\"\n                width=\"550\"\n                height=\"348\"\n            \/>\n        <\/a>\n        <figcaption>\n            <a href=\"#fa-photo-4916\" class=\"js__imageNumbering\">#<\/a>\n            <strong>Das Toolbike No 01 von Monopole sieht nicht nur sehr schick aus, es ist zudem auch funktional und durchdacht.<\/strong> \n        <\/figcaption>\n    <\/figure><\/div>\n<h2>Traumkombo Mahle X35 &amp; Pinion<\/h2>\n<p>Neben einem Mahle X35 Nabenmotor, der dem bis zu einem Gesamtgewicht von 150 kg zugelassenen Fahrrad eine Unterst\u00fctzung von 40 Nm und 250 Watt zukommen l\u00e4sst und \u00fcber einen integrierten 250 Wh Akku gespeist wird, kommen weitere Besonderheiten beim Toolbike No 01 zum Tragen. Am auffallendsten, wenn auch nicht auf den ersten Blick ersichtlich, ist der Lenkmechanismus, der \u00fcber einen Zahnriemen von Gates verf\u00fcgt und ein au\u00dfergew\u00f6hnlich pr\u00e4zises und reibungsloses Lenkverhalten erm\u00f6glichen soll. Den Riemen findet man zudem am Antrieb wieder, wo er in Verbindung mit dem integrierten Pinion-Getriebe f\u00fcr Vortrieb sorgt. Zudem sollen beide System mit ihrer Wartungsarmut \u00fcberzeugen und so lange im Einsatz sein.<\/p>\n<div class=\"js__imageWrap n_post-image-wrap \"><div class=\"n_post-image n_post-image--2col\">\n        <figure>\n            <a id=\"fa-photo-4915\"><\/a>\n            <a href=\"https:\/\/fotos.nimms-rad.de\/p\/4915\" title=\"Nicht nur hinten kommt der Gates Riemen zum Einsatz ...\">\n                <img decoding=\"async\"\n                    src=\"https:\/\/images.mtb-news.de\/aGmZqPpGAy6FRlbz_1TkwL1bb_w=\/320x213\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4915-1aaut3wwdsnj-1678817480_monopole_2022_199-original.jpg\"\n                    srcset=\"https:\/\/images.mtb-news.de\/TKFYzavnGpK1YcOlgYrLvCajuRc=\/1180x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4915-1aaut3wwdsnj-1678817480_monopole_2022_199-original.jpg 1180w, https:\/\/images.mtb-news.de\/EzyJTlNbG0XqoKlC0dzRQjbhQ0Q=\/590x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4915-1aaut3wwdsnj-1678817480_monopole_2022_199-original.jpg 590w, https:\/\/images.mtb-news.de\/5Ucu-2_YTLsCsSogppapDQTor7Y=\/980x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4915-1aaut3wwdsnj-1678817480_monopole_2022_199-original.jpg 980w, https:\/\/images.mtb-news.de\/mHtAJhlQKhEehu8EZ-DbJmni31U=\/490x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4915-1aaut3wwdsnj-1678817480_monopole_2022_199-original.jpg 490w, https:\/\/images.mtb-news.de\/6gulJbuPkwSiN1Q7E6jDzzg1RwY=\/740x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4915-1aaut3wwdsnj-1678817480_monopole_2022_199-original.jpg 740w, https:\/\/images.mtb-news.de\/jWOe9uNLMduxYVGw2Cd7OAbcGT4=\/370x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4915-1aaut3wwdsnj-1678817480_monopole_2022_199-original.jpg 370w, https:\/\/images.mtb-news.de\/-iwUGDYsoHdl3GNNEdi615xKQE0=\/480x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4915-1aaut3wwdsnj-1678817480_monopole_2022_199-original.jpg 480w, https:\/\/images.mtb-news.de\/LRZZ39olE81fZYPXtm_jiE-_sIk=\/160x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4915-1aaut3wwdsnj-1678817480_monopole_2022_199-original.jpg 160w\"\n                    sizes=\"auto, (min-width: 980px) 480px, (min-width: 768px) 370px, (min-width: 480px) 480px, 100vw\"\n                    loading=\"lazy\"\n                    alt=\"Nicht nur hinten kommt der Gates Riemen zum Einsatz ...\"\n                    title=\"Nicht nur hinten kommt der Gates Riemen zum Einsatz ...\"\n                    data-photo-id=\"4915\"\n                    height=\"549\"\n                    width=\"428\"\n                \/>\n            <\/a>\n            <figcaption>\n                <a href=\"#fa-photo-4915\" class=\"js__imageNumbering\">#<\/a>\n                <strong>Nicht nur hinten kommt der Gates Riemen zum Einsatz ...<\/strong> \n            <\/figcaption>\n        <\/figure>\n        <figure>\n            <a id=\"fa-photo-4918\"><\/a>\n            <a href=\"https:\/\/fotos.nimms-rad.de\/p\/4918\" title=\"... auch an der Front findet er mit einem innovativen System eine Heimat.\">\n                <img decoding=\"async\"\n                    src=\"https:\/\/images.mtb-news.de\/88inG6Yn_yDq8dDmj7gmzy8DFdk=\/320x213\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4918-840y5su67yix-1678871178_monopole_2022_200-original.jpg\"\n                    srcset=\"https:\/\/images.mtb-news.de\/sNAb2KzO-xRlJ69V0y6ywD2Gamw=\/1180x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4918-840y5su67yix-1678871178_monopole_2022_200-original.jpg 1180w, https:\/\/images.mtb-news.de\/8TJB_gMCg10NYQ2b5Bzl4yKS4-4=\/590x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4918-840y5su67yix-1678871178_monopole_2022_200-original.jpg 590w, https:\/\/images.mtb-news.de\/t88-WghqM8vk3YFqiT2-yvmwQfE=\/980x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4918-840y5su67yix-1678871178_monopole_2022_200-original.jpg 980w, https:\/\/images.mtb-news.de\/WG_yIlc8wYsfu8tuXUlPWyt1rHQ=\/490x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4918-840y5su67yix-1678871178_monopole_2022_200-original.jpg 490w, https:\/\/images.mtb-news.de\/VintxBltwbKrHpt972BJhPCIppo=\/740x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4918-840y5su67yix-1678871178_monopole_2022_200-original.jpg 740w, https:\/\/images.mtb-news.de\/LFf6TdhuB8SIMvFtBEnIVAAb3Io=\/370x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4918-840y5su67yix-1678871178_monopole_2022_200-original.jpg 370w, https:\/\/images.mtb-news.de\/esnSiWIbVtXdzkefkCajRe3DZyo=\/480x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4918-840y5su67yix-1678871178_monopole_2022_200-original.jpg 480w, https:\/\/images.mtb-news.de\/gLjzfvUbSKxQuE9vztey8pcGra8=\/160x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4918-840y5su67yix-1678871178_monopole_2022_200-original.jpg 160w\"\n                    sizes=\"auto, (min-width: 980px) 480px, (min-width: 768px) 370px, (min-width: 480px) 480px, 100vw\"\n                    loading=\"lazy\"\n                    alt=\"... auch an der Front findet er mit einem innovativen System eine Heimat.\"\n                    title=\"... auch an der Front findet er mit einem innovativen System eine Heimat.\"\n                    data-photo-id=\"4918\"\n                    height=\"549\"\n                    width=\"428\"\n                \/>\n            <\/a>\n            <figcaption>\n                <a href=\"#fa-photo-4918\" class=\"js__imageNumbering\">#<\/a>\n                <strong>... auch an der Front findet er mit einem innovativen System eine Heimat.<\/strong> \n            <\/figcaption>\n        <\/figure>\n    <\/div><\/div>\n<h2>Das kleine Bike f\u00fcr die gro\u00dfe City<\/h2>\n<p>Auch das Gewicht wurde im Auge behalten \u2013 mit nur 22 kg (Herstellerangabe) bringt es f\u00fcr ein Lastenrad erstaunlich wenig auf die Waage. Zwei flexibel anpassbare Gep\u00e4cktr\u00e4ger sollen die Transportanforderungen im urbanen Raum erf\u00fcllen und bieten Platz Einkaufstaschen bis hin zum Transport einer Eurobox. Mit 25 kg k\u00f6nnen die Gep\u00e4cktr\u00e4ger beladen werden und k\u00f6nnen so auch eine Getr\u00e4nkekiste sicher aufnehmen. F\u00fcr einen sicheren Einsatz im Stra\u00dfenverkehr sorgen zudem die schon angebrachten Lampen, die von Supernova stammen.<\/p>\n<div class=\"js__imageWrap n_post-image-wrap \"><figure class=\"n_post-image\">\n        <a id=\"fa-photo-4913\"><\/a>\n        <a href=\"https:\/\/fotos.nimms-rad.de\/p\/4913\" title=\"Auch unterschiedliche Gep\u00e4cktr\u00e4ger werden von Monopole f\u00fcr das Toolbike No 01 angeboten.\">\n            <img decoding=\"async\"\n                src=\"https:\/\/images.mtb-news.de\/pFz_XsQfDKZ05AubYMaorhFCQp8=\/320x202\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4913-j9gbcqkng2wy-1677068651_monopole_2022_110-original.jpg\"\n                srcset=\"https:\/\/images.mtb-news.de\/uc6teCcRD_ifbma2_rtK2nbDj44=\/2400x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4913-j9gbcqkng2wy-1677068651_monopole_2022_110-original.jpg 2400w, https:\/\/images.mtb-news.de\/cD67fkPWOd280qBl5a544jLedZw=\/1200x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4913-j9gbcqkng2wy-1677068651_monopole_2022_110-original.jpg 1200w, https:\/\/images.mtb-news.de\/nVyO1Isxu8GvXvsazf1CnzFTjgU=\/2000x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4913-j9gbcqkng2wy-1677068651_monopole_2022_110-original.jpg 2000w, https:\/\/images.mtb-news.de\/zFoOm46msSgxcJRzLacEp2Ejh4Y=\/1000x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4913-j9gbcqkng2wy-1677068651_monopole_2022_110-original.jpg 1000w, https:\/\/images.mtb-news.de\/S3s3reYnZxN-l41CKQ-RFRKUulI=\/1500x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4913-j9gbcqkng2wy-1677068651_monopole_2022_110-original.jpg 1500w, https:\/\/images.mtb-news.de\/xc0jGw7m-WkrAIz8d0He2QPUJ-g=\/750x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4913-j9gbcqkng2wy-1677068651_monopole_2022_110-original.jpg 750w, https:\/\/images.mtb-news.de\/WAKbo3sIjXvEfHh32awzMnLnQvc=\/480x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4913-j9gbcqkng2wy-1677068651_monopole_2022_110-original.jpg 480w, https:\/\/images.mtb-news.de\/r5BRUIK7Dk5eaJ1Qmo6x6rrAsSg=\/320x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4913-j9gbcqkng2wy-1677068651_monopole_2022_110-original.jpg 320w\"\n                sizes=\"auto, (min-width: 980px) 980px, (min-width: 768px) 750px, (min-width: 481px) 720px, 100vw\"\n                loading=\"lazy\"\n                alt=\"Auch unterschiedliche Gep\u00e4cktr\u00e4ger werden von Monopole f\u00fcr das Toolbike No 01 angeboten.\"\n                title=\"Auch unterschiedliche Gep\u00e4cktr\u00e4ger werden von Monopole f\u00fcr das Toolbike No 01 angeboten.\"\n                data-photo-id=\"4913\"\n                width=\"550\"\n                height=\"347\"\n            \/>\n        <\/a>\n        <figcaption>\n            <a href=\"#fa-photo-4913\" class=\"js__imageNumbering\">#<\/a>\n            <strong>Auch unterschiedliche Gep\u00e4cktr\u00e4ger werden von Monopole f\u00fcr das Toolbike No 01 angeboten.<\/strong> \n        <\/figcaption>\n    <\/figure><\/div>\n<p>Eine weitere Besonderheit ist, dass das Lastenrad in drei Gr\u00f6\u00dfen erh\u00e4ltlich ist. In S, M und L bietet es Fahrer*innen von 1,60 m bis 1,95 m K\u00f6rpergr\u00f6\u00dfe einen entsprechenden Rahmen, um ein komfortables und angenehmes Fahren zu erm\u00f6glichen.<\/p>\n<h2>Verf\u00fcgbarkeit &amp; Preise<\/h2>\n<p>Au\u00dferhalb der Schweiz ist das Gef\u00e4hrt indes noch nicht erh\u00e4ltlich \u2013 in Z\u00fcrich, Basel und Bern k\u00f6nnen Probefahrten vereinbart werden, zudem sollen vorerst nur 75 St\u00fcck produziert werden, die ab Herbst 2023 ausgeliefert werden sollen. Dass der Preis f\u00fcr ein solch limitiertes und handgefertiges Modell nicht ganz g\u00fcnstig ist, sollte ebenfalls klar sein \u2013 7.200 CHF wird das Monopole Toolbike No 01 kosten.<\/p>\n<p>Mehr Infos zum Toolbike No 01 und die Marke Monopole findet ihr hier: <a href=\"https:\/\/monopole.cc\/de\" rel=\"noopener nofollow\">www.monopole.cc<\/a>.<\/p>\n<div class=\"js__imageWrap n_post-image-wrap nocaption\"><figure class=\"n_post-image\">\n        <a id=\"fa-photo-4914\"><\/a>\n        <a href=\"https:\/\/fotos.nimms-rad.de\/p\/4914\" title=\"\">\n            <img decoding=\"async\"\n                src=\"https:\/\/images.mtb-news.de\/cbx5nU05uXVX5vGszbWVHqHQa3c=\/320x202\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4914-hjadruudi4rx-1678441935_monopole_2022_053-original.jpg\"\n                srcset=\"https:\/\/images.mtb-news.de\/_36o73w2a_bDxCPG-MrirHnvmw0=\/2400x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4914-hjadruudi4rx-1678441935_monopole_2022_053-original.jpg 2400w, https:\/\/images.mtb-news.de\/jNxJ3wCEH12nKpwq4nK0FqSD2aM=\/1200x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4914-hjadruudi4rx-1678441935_monopole_2022_053-original.jpg 1200w, https:\/\/images.mtb-news.de\/L1mpINR0aPZOwgW-3wEr3-kSsYA=\/2000x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4914-hjadruudi4rx-1678441935_monopole_2022_053-original.jpg 2000w, https:\/\/images.mtb-news.de\/n044ABUuj1UeZsLUC6V8iFCIVD8=\/1000x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4914-hjadruudi4rx-1678441935_monopole_2022_053-original.jpg 1000w, https:\/\/images.mtb-news.de\/KdQ8O7BKpw4qELXEMA9vl8yQ9Yk=\/1500x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4914-hjadruudi4rx-1678441935_monopole_2022_053-original.jpg 1500w, https:\/\/images.mtb-news.de\/VWV788k0Hqjif2YGmP8g8O70Eho=\/750x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4914-hjadruudi4rx-1678441935_monopole_2022_053-original.jpg 750w, https:\/\/images.mtb-news.de\/1F2qvQOvXgP41YxZDJqp1RYknpw=\/480x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4914-hjadruudi4rx-1678441935_monopole_2022_053-original.jpg 480w, https:\/\/images.mtb-news.de\/MR7IY2zmIGu4zoNpHz1dwihXo-g=\/320x0\/https%3A%2F%2Ffotos.nimms-rad.de%2Ff3%2F0%2F4%2F4914-hjadruudi4rx-1678441935_monopole_2022_053-original.jpg 320w\"\n                sizes=\"auto, (min-width: 980px) 980px, (min-width: 768px) 750px, (min-width: 481px) 720px, 100vw\"\n                loading=\"lazy\"\n                alt=\"\"\n                title=\"\"\n                data-photo-id=\"4914\"\n                width=\"550\"\n                height=\"348\"\n            \/>\n        <\/a>\n        <figcaption>\n            <a href=\"#fa-photo-4914\" class=\"js__imageNumbering\">#<\/a>\n            <strong><\/strong> \n        <\/figcaption>\n    <\/figure><\/div>\n<p class=\"mtbn-call-to-action\">Was sagt ihr zum Monopol Toolbike No 01<\/p>\n<div class=\"my-12 flex flex-row flex-nowrap w-full\"><div class=\"h-4 bg-brand-300 flex-grow flex-shrink-0 basis-0\"><\/div><div class=\"h-4 bg-gradient-to-r from-brand-300 to-transparent w-2\"><\/div><span class=\"text-gray-500 font-bold mx-4 leading-none\">Infos und Bilder: Monopole<\/span><div class=\"h-4 bg-gradient-to-r from-transparent to-brand-300 w-2\"><\/div><div class=\"h-4 bg-brand-300 flex-grow flex-shrink-0 basis-0\"><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mit dem Toolbike No 01 stellt die Schweizer Marke Monopole ihr erstes Lastenrad vor \u2013 das Gef\u00e4hrt l\u00e4uft mit elektrischer Unterst\u00fctzung, besitzt eine Riemenlenkung, ist in 3 Gr\u00f6\u00dfen erh\u00e4ltlich und der Rahmen wird in Europa hergestellt.<\/p>\n","protected":false},"author":36,"featured_media":41253,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2419],"tags":[2619],"marke":[],"class_list":["post-41251","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lastenrad-cargobike","tag-magazin_feature"],"acf":[],"yoast_head":"<title>Monopole Toolbike No 01 Lastenrad: Das Schweizer Taschenmesser unter den Cargobikes - Nimms Rad<\/title>\n<meta name=\"description\" content=\"Monopol stellt mit dem Toolbike No 01 ein Lastenrad vor, dass nicht nur funktional ist sondern auch beim Design einiges bietet.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nimms-rad.de\/news\/monopol-toolbike-no-01-lastenrad\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Monopole Toolbike No 01 Lastenrad: Das Schweizer Taschenmesser unter den Cargobikes - Nimms Rad\" \/>\n<meta property=\"og:description\" content=\"Monopol stellt mit dem Toolbike No 01 ein Lastenrad vor, dass nicht nur funktional ist sondern auch beim Design einiges bietet.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nimms-rad.de\/news\/monopol-toolbike-no-01-lastenrad\/\" \/>\n<meta property=\"og:site_name\" content=\"Nimms Rad\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nimmsrad\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-15T07:00:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-12T12:35:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nimms-rad.de\/news\/wp-content\/uploads\/2023\/04\/monopole-toolbike-no-01-2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1261\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dennis Haas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nimmsrad\" \/>\n<meta name=\"twitter:site\" content=\"@nimmsrad\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dennis Haas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/monopol-toolbike-no-01-lastenrad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/monopol-toolbike-no-01-lastenrad\\\/\"},\"author\":{\"name\":\"Dennis Haas\",\"@id\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/#\\\/schema\\\/person\\\/b33c4bf22c6b3a9b0fc5e7ce594a78a1\"},\"headline\":\"Monopole Toolbike No 01 Lastenrad: Das Schweizer Taschenmesser unter den Cargobikes\",\"datePublished\":\"2023-04-15T07:00:20+00:00\",\"dateModified\":\"2024-01-12T12:35:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/monopol-toolbike-no-01-lastenrad\\\/\"},\"wordCount\":502,\"publisher\":{\"@id\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/monopol-toolbike-no-01-lastenrad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/monopole-toolbike-no-01-2.jpeg\",\"keywords\":[\"magazin_feature\"],\"articleSection\":[\"Lastenrad\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/monopol-toolbike-no-01-lastenrad\\\/\",\"url\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/monopol-toolbike-no-01-lastenrad\\\/\",\"name\":\"Monopole Toolbike No 01 Lastenrad: Das Schweizer Taschenmesser unter den Cargobikes - Nimms Rad\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/monopol-toolbike-no-01-lastenrad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/monopol-toolbike-no-01-lastenrad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/monopole-toolbike-no-01-2.jpeg\",\"datePublished\":\"2023-04-15T07:00:20+00:00\",\"dateModified\":\"2024-01-12T12:35:46+00:00\",\"description\":\"Monopol stellt mit dem Toolbike No 01 ein Lastenrad vor, dass nicht nur funktional ist sondern auch beim Design einiges bietet.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/monopol-toolbike-no-01-lastenrad\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/monopol-toolbike-no-01-lastenrad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/monopol-toolbike-no-01-lastenrad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/monopole-toolbike-no-01-2.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/monopole-toolbike-no-01-2.jpeg\",\"width\":2000,\"height\":1261},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/monopol-toolbike-no-01-lastenrad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Monopole Toolbike No 01 Lastenrad: Das Schweizer Taschenmesser unter den Cargobikes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/\",\"name\":\"Nimms Rad\",\"description\":\"Urban Mobility\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/#organization\",\"name\":\"Nimms Rad\",\"url\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/podcast-icon.png\",\"contentUrl\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/podcast-icon.png\",\"width\":3000,\"height\":3000,\"caption\":\"Nimms Rad\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/nimmsrad\",\"https:\\\/\\\/x.com\\\/nimmsrad\",\"http:\\\/\\\/instagram.com\\\/nimmsrad\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC9O2yrPgIxmo2jn_j_pHNJg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/#\\\/schema\\\/person\\\/b33c4bf22c6b3a9b0fc5e7ce594a78a1\",\"name\":\"Dennis Haas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-dennis-profil-9484-96x96.jpg\",\"url\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-dennis-profil-9484-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-dennis-profil-9484-96x96.jpg\",\"caption\":\"Dennis Haas\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/ptrbcks\\\/\"],\"url\":\"https:\\\/\\\/www.nimms-rad.de\\\/news\\\/author\\\/dennis\\\/\"}]}<\/script>","yoast_head_json":{"title":"Monopole Toolbike No 01 Lastenrad: Das Schweizer Taschenmesser unter den Cargobikes - Nimms Rad","description":"Monopol stellt mit dem Toolbike No 01 ein Lastenrad vor, dass nicht nur funktional ist sondern auch beim Design einiges bietet.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nimms-rad.de\/news\/monopol-toolbike-no-01-lastenrad\/","og_locale":"de_DE","og_type":"article","og_title":"Monopole Toolbike No 01 Lastenrad: Das Schweizer Taschenmesser unter den Cargobikes - Nimms Rad","og_description":"Monopol stellt mit dem Toolbike No 01 ein Lastenrad vor, dass nicht nur funktional ist sondern auch beim Design einiges bietet.","og_url":"https:\/\/www.nimms-rad.de\/news\/monopol-toolbike-no-01-lastenrad\/","og_site_name":"Nimms Rad","article_publisher":"https:\/\/www.facebook.com\/nimmsrad","article_published_time":"2023-04-15T07:00:20+00:00","article_modified_time":"2024-01-12T12:35:46+00:00","og_image":[{"width":2000,"height":1261,"url":"https:\/\/www.nimms-rad.de\/news\/wp-content\/uploads\/2023\/04\/monopole-toolbike-no-01-2.jpeg","type":"image\/jpeg"}],"author":"Dennis Haas","twitter_card":"summary_large_image","twitter_creator":"@nimmsrad","twitter_site":"@nimmsrad","twitter_misc":{"Verfasst von":"Dennis Haas","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.nimms-rad.de\/news\/monopol-toolbike-no-01-lastenrad\/#article","isPartOf":{"@id":"https:\/\/www.nimms-rad.de\/news\/monopol-toolbike-no-01-lastenrad\/"},"author":{"name":"Dennis Haas","@id":"https:\/\/www.nimms-rad.de\/news\/#\/schema\/person\/b33c4bf22c6b3a9b0fc5e7ce594a78a1"},"headline":"Monopole Toolbike No 01 Lastenrad: Das Schweizer Taschenmesser unter den Cargobikes","datePublished":"2023-04-15T07:00:20+00:00","dateModified":"2024-01-12T12:35:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.nimms-rad.de\/news\/monopol-toolbike-no-01-lastenrad\/"},"wordCount":502,"publisher":{"@id":"https:\/\/www.nimms-rad.de\/news\/#organization"},"image":{"@id":"https:\/\/www.nimms-rad.de\/news\/monopol-toolbike-no-01-lastenrad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nimms-rad.de\/news\/wp-content\/uploads\/2023\/04\/monopole-toolbike-no-01-2.jpeg","keywords":["magazin_feature"],"articleSection":["Lastenrad"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.nimms-rad.de\/news\/monopol-toolbike-no-01-lastenrad\/","url":"https:\/\/www.nimms-rad.de\/news\/monopol-toolbike-no-01-lastenrad\/","name":"Monopole Toolbike No 01 Lastenrad: Das Schweizer Taschenmesser unter den Cargobikes - Nimms Rad","isPartOf":{"@id":"https:\/\/www.nimms-rad.de\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nimms-rad.de\/news\/monopol-toolbike-no-01-lastenrad\/#primaryimage"},"image":{"@id":"https:\/\/www.nimms-rad.de\/news\/monopol-toolbike-no-01-lastenrad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nimms-rad.de\/news\/wp-content\/uploads\/2023\/04\/monopole-toolbike-no-01-2.jpeg","datePublished":"2023-04-15T07:00:20+00:00","dateModified":"2024-01-12T12:35:46+00:00","description":"Monopol stellt mit dem Toolbike No 01 ein Lastenrad vor, dass nicht nur funktional ist sondern auch beim Design einiges bietet.","breadcrumb":{"@id":"https:\/\/www.nimms-rad.de\/news\/monopol-toolbike-no-01-lastenrad\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nimms-rad.de\/news\/monopol-toolbike-no-01-lastenrad\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.nimms-rad.de\/news\/monopol-toolbike-no-01-lastenrad\/#primaryimage","url":"https:\/\/www.nimms-rad.de\/news\/wp-content\/uploads\/2023\/04\/monopole-toolbike-no-01-2.jpeg","contentUrl":"https:\/\/www.nimms-rad.de\/news\/wp-content\/uploads\/2023\/04\/monopole-toolbike-no-01-2.jpeg","width":2000,"height":1261},{"@type":"BreadcrumbList","@id":"https:\/\/www.nimms-rad.de\/news\/monopol-toolbike-no-01-lastenrad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nimms-rad.de\/news\/"},{"@type":"ListItem","position":2,"name":"Monopole Toolbike No 01 Lastenrad: Das Schweizer Taschenmesser unter den Cargobikes"}]},{"@type":"WebSite","@id":"https:\/\/www.nimms-rad.de\/news\/#website","url":"https:\/\/www.nimms-rad.de\/news\/","name":"Nimms Rad","description":"Urban Mobility","publisher":{"@id":"https:\/\/www.nimms-rad.de\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nimms-rad.de\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.nimms-rad.de\/news\/#organization","name":"Nimms Rad","url":"https:\/\/www.nimms-rad.de\/news\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.nimms-rad.de\/news\/#\/schema\/logo\/image\/","url":"https:\/\/www.nimms-rad.de\/news\/wp-content\/uploads\/2015\/06\/podcast-icon.png","contentUrl":"https:\/\/www.nimms-rad.de\/news\/wp-content\/uploads\/2015\/06\/podcast-icon.png","width":3000,"height":3000,"caption":"Nimms Rad"},"image":{"@id":"https:\/\/www.nimms-rad.de\/news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nimmsrad","https:\/\/x.com\/nimmsrad","http:\/\/instagram.com\/nimmsrad","https:\/\/www.youtube.com\/channel\/UC9O2yrPgIxmo2jn_j_pHNJg"]},{"@type":"Person","@id":"https:\/\/www.nimms-rad.de\/news\/#\/schema\/person\/b33c4bf22c6b3a9b0fc5e7ce594a78a1","name":"Dennis Haas","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.nimms-rad.de\/news\/wp-content\/uploads\/2024\/03\/cropped-dennis-profil-9484-96x96.jpg","url":"https:\/\/www.nimms-rad.de\/news\/wp-content\/uploads\/2024\/03\/cropped-dennis-profil-9484-96x96.jpg","contentUrl":"https:\/\/www.nimms-rad.de\/news\/wp-content\/uploads\/2024\/03\/cropped-dennis-profil-9484-96x96.jpg","caption":"Dennis Haas"},"sameAs":["https:\/\/www.instagram.com\/ptrbcks\/"],"url":"https:\/\/www.nimms-rad.de\/news\/author\/dennis\/"}]}},"wp-worthy-pixel":{"ignored":false,"public":"4d48e111fbc5492ead4c39357c5a0200","server":"vg09.met.vgwort.de","url":"https:\/\/vg09.met.vgwort.de\/na\/4d48e111fbc5492ead4c39357c5a0200"},"wp-worthy-type":"normal","custom":{"popular_score":5527,"views":2870,"comments":1,"original_site":"","original_id":""},"_links":{"self":[{"href":"https:\/\/www.nimms-rad.de\/news\/wp-json\/wp\/v2\/posts\/41251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nimms-rad.de\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nimms-rad.de\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nimms-rad.de\/news\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nimms-rad.de\/news\/wp-json\/wp\/v2\/comments?post=41251"}],"version-history":[{"count":8,"href":"https:\/\/www.nimms-rad.de\/news\/wp-json\/wp\/v2\/posts\/41251\/revisions"}],"predecessor-version":[{"id":47294,"href":"https:\/\/www.nimms-rad.de\/news\/wp-json\/wp\/v2\/posts\/41251\/revisions\/47294"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nimms-rad.de\/news\/wp-json\/wp\/v2\/media\/41253"}],"wp:attachment":[{"href":"https:\/\/www.nimms-rad.de\/news\/wp-json\/wp\/v2\/media?parent=41251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nimms-rad.de\/news\/wp-json\/wp\/v2\/categories?post=41251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nimms-rad.de\/news\/wp-json\/wp\/v2\/tags?post=41251"},{"taxonomy":"marke","embeddable":true,"href":"https:\/\/www.nimms-rad.de\/news\/wp-json\/wp\/v2\/marke?post=41251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}